{"id":31880,"date":"2026-07-27T09:02:45","date_gmt":"2026-07-27T07:02:45","guid":{"rendered":"https:\/\/hts-mct.com\/a-propos-de-hts-2\/"},"modified":"2026-09-01T15:12:03","modified_gmt":"2026-09-01T13:12:03","slug":"a-propos-de-hts-2","status":"publish","type":"page","link":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/","title":{"rendered":"\u00c0 propos de HTS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"31880\" class=\"elementor elementor-31880 elementor-28966\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-570a84d7 e-con-full e-flex e-con e-parent\" data-id=\"570a84d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41978715 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"41978715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">HTS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca6386 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3ca6386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions de scellage de s\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24384eac elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"24384eac\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"breadcrumbs\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav id=\"breadcrumbs\"><span><span><a href=\"https:\/\/hts-mct.com\/fr\/\">Home<\/a><\/span><\/span><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23c25324 e-con-full e-flex e-con e-parent\" data-id=\"23c25324\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3241e511 e-con-full e-flex e-con e-child\" data-id=\"3241e511\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60aa80c6 elementor-widget elementor-widget-heading\" data-id=\"60aa80c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fabricant europ\u00e9en de syst\u00e8mes d'\u00e9tanch\u00e9it\u00e9 MCT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50ae052c elementor-widget elementor-widget-text-editor\" data-id=\"50ae052c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>HTS (Hawke Transit System), une <\/strong>soci\u00e9t\u00e9 du groupe JOVE, est sp\u00e9cialis\u00e9e dans la conception et la fabrication de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 pour le passage de c\u00e2bles multiples et de canalisations destin\u00e9s aux infrastructures critiques et aux environnements industriels exigeants. Forte de plus de 30 ans d\u2019exp\u00e9rience, HTS d\u00e9veloppe des solutions certifi\u00e9es con\u00e7ues pour prot\u00e9ger les installations contre des risques tels que l\u2019incendie, l\u2019explosion, les inondations, la fum\u00e9e et les infiltrations de gaz, contribuant ainsi \u00e0 garantir la s\u00e9curit\u00e9, l\u2019int\u00e9grit\u00e9 et la continuit\u00e9 des op\u00e9rations. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cefea0 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5cefea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hts-mct.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prise de contact avec HTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30daf004 e-con-full e-flex e-con e-child\" data-id=\"30daf004\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ad6423 e-con-full e-flex e-con e-parent\" data-id=\"8ad6423\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef9e20e elementor-widget elementor-widget-heading\" data-id=\"ef9e20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Secteurs d'activit\u00e9 que nous desservons<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1b8ea5 elementor-widget elementor-widget-text-editor\" data-id=\"c1b8ea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment les syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 HTS r\u00e9pondent aux besoins d&rsquo;applications critiques dans des secteurs exigeants \u00e0 travers le monde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3f8c7 elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"2a3f8c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Marine&quot;,&quot;_id&quot;:&quot;819abf8&quot;},{&quot;slide_title&quot;:&quot;Infrastructure&quot;,&quot;_id&quot;:&quot;8c547bf&quot;},{&quot;slide_title&quot;:&quot;Offshore Oil &amp; Gas&quot;,&quot;_id&quot;:&quot;b4d890b&quot;},{&quot;slide_title&quot;:&quot;Manufacturing Industry&quot;,&quot;_id&quot;:&quot;8c942f0&quot;},{&quot;slide_title&quot;:&quot;Power Generation&quot;,&quot;_id&quot;:&quot;0120d60&quot;},{&quot;slide_title&quot;:&quot;Process Industries&quot;,&quot;_id&quot;:&quot;a6a760b&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5135523 e-flex e-con-boxed e-con e-child\" data-id=\"5135523\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c76332b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c76332b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/solutions-detancheite-pour-les-applications-maritimes\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 57.84 49.58\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><path class=\"cls-1\" d=\"M30.05,14h-2.41c-.55,0-1-.45-1-1s.45-1,1-1h2.41c.55,0,1,.45,1,1s-.45,1-1,1ZM24.6,12h-2.41c-.55,0-1,.45-1,1s.45,1,1,1h2.41c.55,0,1-.45,1-1s-.45-1-1-1ZM32.92,14h2.41c.55,0,1-.45,1-1s-.45-1-1-1h-2.41c-.55,0-1,.45-1,1s.45,1,1,1ZM57.84,38.23v3.15c0,.7-.35,1.33-.95,1.7l-3.77,2.33v2.17c0,1.1-.9,2-2,2H6.73c-1.1,0-2-.9-2-2v-2.17l-3.78-2.33c-.59-.37-.95-1-.95-1.7v-3.15c0-.71.37-1.33.93-1.69L3.62,9.04c.1-1.03.96-1.81,1.99-1.81h4.01c1.1,0,2,.9,2,2v27.15c.72.3,1.22,1.02,1.22,1.84v1.55h8.41l-5.57-12.21s0,0,0,0c0,0,0,0,0,0l-1.68-3.68c-.22-.49-.02-1.07.46-1.31.84-.42,1.75-.88,2.69-1.34l.75-11.19c.09-1.52,1.37-2.72,2.95-2.8l.97-5.13c.23-1.23,1.31-2.12,2.56-2.12h8.9c1.25,0,2.33.89,2.56,2.12l.97,5.14c1.51.15,2.71,1.31,2.8,2.79l.75,11.18c.94.47,1.85.93,2.69,1.34.48.24.69.82.46,1.31l-7.25,15.89h8.75v-1.55c0-.75.42-1.4,1.03-1.74V9.24c0-1.1.9-2,2-2h4.01c1.03,0,1.89.78,1.99,1.81l2.67,27.41c.65.33,1.1,1,1.1,1.78ZM48.06,36.23h6.65l-2.63-26.99h-4.01v26.99ZM23.8,2.49l-.9,4.74h11.88l-.9-4.74c-.05-.28-.3-.49-.59-.49h-8.9c-.29,0-.54.21-.59.49ZM19.24,20.2c4.26-2.13,8.48-4.25,8.97-4.53.32-.22.8-.22,1.12,0,.5.28,4.71,2.4,8.97,4.53l-.67-10.02c-.03-.53-.53-.95-1.11-.95h-15.49c-.58,0-1.08.42-1.11.94l-.67,10.03ZM16.23,23.94l.83,1.83c2.97-1.49,10.61-5.33,11.17-5.63.3-.19.74-.19,1.05,0,.57.31,8.22,4.15,11.18,5.64l.84-1.83c-.55-.28-11.58-5.8-12.54-6.36-.96.56-11.29,5.74-12.54,6.36ZM23.45,39.78h10.63l5.56-12.18c-6.66-3.31-9.59-4.77-10.88-5.54-1.28.76-4.21,2.22-10.87,5.53l5.56,12.19ZM2.97,36.23h6.65V9.24h-4.01l-2.63,26.99ZM55.84,38.23h-.03s0,0,0,0h-8.78v1.55c0,1.1-.9,2-2,2H12.84c-1.1,0-2-.9-2-2v-1.55H2v3.15l3.78,2.33c.59.36.95,1.01.95,1.7v2.17h44.39v-2.17c0-.69.37-1.34.95-1.7l3.77-2.32v-3.15ZM26.61,5.62h4.49c.55,0,1-.45,1-1s-.45-1-1-1h-4.49c-.55,0-1,.45-1,1s.45,1,1,1Z\"><\/path><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d3f66 elementor-widget elementor-widget-heading\" data-id=\"b0d3f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/solutions-detancheite-pour-les-applications-maritimes\/\">Marine<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d360619 e-flex e-con-boxed e-con e-child\" data-id=\"d360619\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b44f8c7 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b44f8c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/infrastructures\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 50 50\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><g><path class=\"cls-1\" d=\"M48,44v-11c0-.55-.45-1-1-1s-1,.45-1,1v11h-2v-10c0-1.1-.9-2-2-2h-10c-1.1,0-2,.9-2,2v10h-10v-10c0-1.1-.9-2-2-2h-10c-1.1,0-2,.9-2,2v10h-2v-22h42v7c0,.55.45,1,1,1s1-.45,1-1V9c0-.55-.45-1-1-1h-3c-.27,0-.52.11-.71.29l-3.29,3.3v-2.59c0-.55-.45-1-1-1h-3c-.27,0-.52.11-.71.29l-3.29,3.3v-2.59c0-.55-.45-1-1-1h-3c-.27,0-.52.11-.71.29l-5,5c-.18.19-.29.44-.29.71v6h-2.14L17.12,1.7c-.15-.98-.98-1.7-1.98-1.7h-6.28c-1,0-1.83.72-1.98,1.7l-2.74,18.3h-.14c-1.1,0-2,.9-2,2v22c-1.1,0-2,.9-2,2v2c0,1.1.9,2,2,2h11c.55,0,1-.45,1-1s-.45-1-1-1H2v-2h46v2h-31c-.55,0-1,.45-1,1s.45,1,1,1h31c1.1,0,2-.9,2-2v-2c0-1.1-.9-2-2-2ZM40,14.41l4.41-4.41h1.59v10h-6v-5.59ZM32,14.41l4.41-4.41h1.59v10h-6v-5.59ZM24,14.41l4.41-4.41h1.59v10h-6v-5.59ZM8.86,2h6.28l.3,2h-6.88l.3-2ZM8.26,6h7.48l.3,2H7.96l.3-2ZM7.66,10h8.68l1.5,10H6.16l1.5-10ZM12,44h-4v-10h4v10ZM18,44h-4v-10h4v10ZM36,44h-4v-10h4v10ZM42,44h-4v-10h4v10Z\"><\/path><path class=\"cls-1\" d=\"M7,24c-.55,0-1,.45-1,1v4c0,.55.45,1,1,1h36c.55,0,1-.45,1-1v-4c0-.55-.45-1-1-1H7ZM42,28H8v-2h34v2Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7951dd elementor-widget elementor-widget-heading\" data-id=\"a7951dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/infrastructures\/\">Infrastructures<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5a7f96 e-flex e-con-boxed e-con e-child\" data-id=\"e5a7f96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9142ccb elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9142ccb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/petrole-et-gaz-offshore\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 50 50.01\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><g><path class=\"cls-1\" d=\"M49.71,48.29l-3-3c-.22-.22-.46-.4-.71-.57v-6.72h3c.55,0,1-.45,1-1v-6c0-.55-.45-1-1-1h-1v-3c.55,0,1-.45,1-1s-.45-1-1-1v-1c0-.55-.45-1-1-1s-1,.45-1,1v1c-.55,0-1,.45-1,1s.45,1,1,1v3h-3v-9c0-.55-.45-1-1-1h-22v-2h4c.73,0,1.23-.79.89-1.45l-4-8c-.16-.34-.51-.55-.89-.55h-4v-2.15l20-3.34v5.49c0,.55.45,1,1,1,1.1,0,2,.9,2,2s-.9,2-2,2-2-.9-2-2c0-.55-.45-1-1-1s-1,.45-1,1c0,2.21,1.79,4,4,4s4-1.79,4-4c0-1.86-1.28-3.43-3-3.87V2.18l1.16-.19c.55-.09.92-.61.83-1.15-.09-.55-.61-.92-1.15-.83l-22.84,3.81V1C16,.45,15.55,0,15,0h-4c-.55,0-1,.45-1,1v7h-2c-.55,0-1,.45-1,1v8c0,.55.45,1,1,1h2v2h-2c-.55,0-1,.45-1,1v9h-3v-3c.55,0,1-.45,1-1s-.45-1-1-1v-1c0-.55-.45-1-1-1s-1,.45-1,1v1c-.55,0-1,.45-1,1s.45,1,1,1v3h-1C.45,30,0,30.45,0,31v6c0,.55.45,1,1,1h3v6.72c-.25.17-.49.35-.71.57l-3,3c-.39.39-.39,1.03,0,1.42s1.03.39,1.42,0l3-3c1.22-1.23,3.36-1.23,4.58,0,2.05,2.04,5.37,2.04,7.42,0,1.22-1.23,3.36-1.23,4.58,0,2.05,2.04,5.37,2.04,7.42,0,1.22-1.23,3.36-1.23,4.58,0,2.05,2.04,5.37,2.04,7.42,0,1.22-1.23,3.36-1.23,4.58,0,0,0,3,3,3,3,.39.39,1.04.38,1.42,0,.39-.39.39-1.03,0-1.42ZM12,2h2v6h-2V2ZM9,16v-6h10.38l3,6h-13.38ZM18,18v2h-6v-2h6ZM9,22h32v8h-10v-5c0-.55-.45-1-1-1h-10c-.55,0-1,.45-1,1v5h-10v-8ZM29,26v4h-8v-4h8ZM10,44.72c-1.18-.83-2.63-1.13-4-.86v-5.86h4v6.72ZM24,46.07c-.47-.15-.92-.4-1.29-.78-2.05-2.04-5.37-2.04-7.42,0-.89.89-2.17,1.14-3.29.78v-8.07h7v3c0,.55.45,1,1,1h4v4.07ZM21,40v-2h8v2h-8ZM38,46.07c-1.12.36-2.4.11-3.29-.78-2.05-2.04-5.37-2.04-7.42,0-.37.38-.82.63-1.29.78v-4.07h4c.55,0,1-.45,1-1v-3h7v8.07ZM44,43.86c-1.37-.27-2.82.03-4,.86v-6.72h4v5.86ZM2,36v-4h46v4H2Z\"><\/path><circle class=\"cls-1\" cx=\"13\" cy=\"13\" r=\"1\"><\/circle><circle class=\"cls-1\" cx=\"17\" cy=\"13\" r=\"1\"><\/circle><circle class=\"cls-1\" cx=\"12\" cy=\"26\" r=\"1\"><\/circle><circle class=\"cls-1\" cx=\"16\" cy=\"26\" r=\"1\"><\/circle><circle class=\"cls-1\" cx=\"38\" cy=\"26\" r=\"1\"><\/circle><circle class=\"cls-1\" cx=\"34\" cy=\"26\" r=\"1\"><\/circle><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f9171 elementor-widget elementor-widget-heading\" data-id=\"d1f9171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/petrole-et-gaz-offshore\/\">P\u00e9trole et gaz offshore<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47be233 e-flex e-con-boxed e-con e-child\" data-id=\"47be233\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4d11e2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e4d11e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/industrie-manufacturiere\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 50 50\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><g><path class=\"cls-1\" d=\"M48,10.95c-.03-.53-.47-.95-1-.95h-8c-.53,0-.97.42-1,.95l-.42,8.05-7.1-3.88c-.15-.08-.31-.12-.48-.12h-4V7c0-3.86-3.14-7-7-7s-7,3.14-7,7v21h-3c-.55,0-1,.45-1,1v6h-1c-3.86,0-7,3.14-7,7v7c0,.55.45,1,1,1h4c.55,0,1-.45,1-1v-7c0-.55.45-1,1-1h1v8c0,.55.45,1,1,1h40c.27,0,.54-.11.73-.31.18-.2.28-.47.27-.74l-2-38ZM8,39h-1c-1.65,0-3,1.35-3,3v6h-2v-6c0-2.76,2.24-5,5-5h1v2ZM39.95,12h6.1l.16,3h-6.42l.16-3ZM26,17h3.74l7.72,4.22-.12,2.19-7.86-4.29c-.15-.08-.31-.12-.48-.12h-3v-2ZM26,21h2.75l8.48,4.62-.13,2.38h-11.1v-7ZM14,7c0-2.76,2.24-5,5-5s5,2.24,5,5v1h-10v-1ZM14,10h10v2h-10v-2ZM14,14h10v14h-10v-14ZM24,48h-6v-6h6v6ZM32,48h-6v-6h6v6ZM40,48h-6v-7c0-.55-.45-1-1-1h-16c-.55,0-1,.45-1,1v7h-6v-18h30v18ZM42,48v-19c0-.55-.45-1-1-1h-1.9l.15-2.85.43-8.15h6.63l1.64,31h-5.95Z\"><\/path><path class=\"cls-1\" d=\"M35,38c.55,0,1-.45,1-1v-4c0-.55-.45-1-1-1H15c-.55,0-1,.45-1,1v4c0,.55.45,1,1,1h20ZM24,36h-3v-2h3v2ZM26,34h3v2h-3v-2ZM34,36h-3v-2h3v2ZM16,34h3v2h-3v-2Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7cb855 elementor-widget elementor-widget-heading\" data-id=\"f7cb855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/industrie-manufacturiere\/\">Industrie manufacturi\u00e8re<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6649e84 e-flex e-con-boxed e-con e-child\" data-id=\"6649e84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd9fd6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3fd9fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/production-delectricite\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 50 50\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><g><path class=\"cls-1\" d=\"M49,48h-1.06l-.62-9.28s0-.02-.01-.03l-1.24-18.7c.52-.04.93-.46.93-.99s-.45-1-1-1h-2v-2c.55,0,1-.45,1-1s-.45-1-1-1v-1c0-.55-.45-1-1-1s-1,.45-1,1v1c-.55,0-1,.45-1,1s.45,1,1,1v2h-4v-2c.55,0,1-.45,1-1s-.45-1-1-1v-1c0-.55-.45-1-1-1s-1,.45-1,1v1c-.55,0-1,.45-1,1s.45,1,1,1v2h-2c-.55,0-1,.45-1,1s.41.95.93.99l-.53,8.01h-.82c-1.38,0-2.59.88-3.03,2.18-.16.49-.62.82-1.13.82h-.42v-14c0-.55-.45-1-1-1h-1V1c0-.55-.45-1-1-1H5c-.55,0-1,.45-1,1v15h-1c-.55,0-1,.45-1,1v31h-1c-.55,0-1,.45-1,1s.45,1,1,1h48c.55,0,1-.45,1-1s-.45-1-1-1ZM6,2h18v14H6V2ZM19,48h-8v-6h8v6ZM26,48h-5v-6c.55,0,1-.45,1-1s-.45-1-1-1h-12c-.55,0-1,.45-1,1s.45,1,1,1v6h-5v-30h22v30ZM33.03,33.55s0,.03-.01.05l-.68,10.22h0s-.01.25-.01.25l-.27,3.93h-4.06v-15h.42c1.38,0,2.59-.88,3.03-2.18.16-.49.62-.82,1.13-.82h.68l-.23,3.55ZM45.22,37.3l-9.25-3.3,8.82-3.14.43,6.44ZM43.28,20h.78l.47,7.06-8.01-2.87,6.76-4.19ZM35.94,20h3.55l-3.71,2.3.16-2.3ZM35.54,25.97l8.49,3.03-8.91,3.17.42-6.2ZM34.89,35.74l9.13,3.26-9.58,3.42.45-6.68ZM34.07,48l.14-2.18,3.93,2.18h-4.07ZM42.26,48l-6.84-3.8,10.02-3.58.49,7.38h-3.67Z\"><\/path><path class=\"cls-1\" d=\"M13,8h-2.38l1.28-2.55c.25-.49.05-1.09-.45-1.34s-1.09-.05-1.34.45l-2,4c-.16.31-.14.68.04.97.18.29.5.47.85.47h2.38l-1.28,2.55c-.25.49-.05,1.09.45,1.34.49.24,1.1.04,1.34-.45l2-4c.16-.31.14-.68-.04-.97-.18-.29-.5-.47-.85-.47Z\"><\/path><path class=\"cls-1\" d=\"M21,8h-4c-.55,0-1,.45-1,1s.45,1,1,1h4c.55,0,1-.45,1-1s-.45-1-1-1Z\"><\/path><path class=\"cls-1\" d=\"M21,12h-4c-.55,0-1,.45-1,1s.45,1,1,1h4c.55,0,1-.45,1-1s-.45-1-1-1Z\"><\/path><path class=\"cls-1\" d=\"M21,4h-4c-.55,0-1,.45-1,1s.45,1,1,1h4c.55,0,1-.45,1-1s-.45-1-1-1Z\"><\/path><path class=\"cls-1\" d=\"M13,20h-6c-.55,0-1,.45-1,1v6c0,.55.45,1,1,1h6c.55,0,1-.45,1-1v-6c0-.55-.45-1-1-1ZM12,26h-4v-4h4v4Z\"><\/path><path class=\"cls-1\" d=\"M23,20h-6c-.55,0-1,.45-1,1v6c0,.55.45,1,1,1h6c.55,0,1-.45,1-1v-6c0-.55-.45-1-1-1ZM22,26h-4v-4h4v4Z\"><\/path><path class=\"cls-1\" d=\"M13,30h-6c-.55,0-1,.45-1,1v6c0,.55.45,1,1,1h6c.55,0,1-.45,1-1v-6c0-.55-.45-1-1-1ZM12,36h-4v-4h4v4Z\"><\/path><path class=\"cls-1\" d=\"M23,30h-6c-.55,0-1,.45-1,1v6c0,.55.45,1,1,1h6c.55,0,1-.45,1-1v-6c0-.55-.45-1-1-1ZM22,36h-4v-4h4v4Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c2160 elementor-widget elementor-widget-heading\" data-id=\"b8c2160\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/production-delectricite\/\">Production d'\u00e9lectricit\u00e9<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81e8516 e-flex e-con-boxed e-con e-child\" data-id=\"81e8516\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82af9e3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"82af9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/industries-de-transformation\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_2\" data-name=\"Capa 2\" viewBox=\"0 0 50 50\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Capa_1-2\" data-name=\"Capa 1\"><path class=\"cls-1\" d=\"M49,48h-3v-5.08c2.45-2.2,4-5.38,4-8.92,0-4.43-2.42-8.3-6-10.38v-4.62c0-.55-.45-1-1-1h-4V4c0-2.21-1.79-4-4-4H13c-2.21,0-4,1.79-4,4v2.09c-2.83.48-5,2.94-5,5.91v16.7c-1.26,1.78-2,3.95-2,6.3v13h-1c-.55,0-1,.45-1,1s.45,1,1,1h48c.55,0,1-.45,1-1s-.45-1-1-1ZM48,34c0,1.04-.16,2.05-.46,3h-19.08c-.3-.95-.46-1.96-.46-3s.16-2.05.46-3h19.08c.3.95.46,1.96.46,3ZM46.65,29h-17.3c1.74-2.98,4.96-5,8.65-5s6.91,2.02,8.65,5ZM42,20v2.7c-1.25-.45-2.6-.7-4-.7s-2.75.25-4,.7v-2.7h8ZM6,12c0-2.21,1.79-4,4-4s4,1.79,4,4v2H6v-2ZM6,16h8v2H6v-2ZM6,20h8v4.05c-.33-.03-.66-.05-1-.05-2.66,0-5.1.95-7,2.52v-6.52ZM16,48h-6v-4h6v4ZM22,48h-4v-5c0-.55-.45-1-1-1h-8c-.55,0-1,.45-1,1v5h-4v-8h18v8ZM22,38H4v-3c0-4.96,4.04-9,9-9s9,4.04,9,9v3ZM30,48h-6v-13c0-5.02-3.39-9.26-8-10.57v-12.43c0-2.97-2.17-5.43-5-5.91v-2.09c0-1.1.9-2,2-2h22c1.1,0,2,.9,2,2v14h-4c-.55,0-1,.45-1,1v4.62c-3.58,2.08-6,5.95-6,10.38,0,3.54,1.55,6.72,4,8.92v5.08ZM34.11,48h-2.11v-3.62c.75.43,1.55.8,2.39,1.06l-.28,2.56ZM36.12,48l.24-2.13c.54.08,1.08.13,1.64.13s1.1-.05,1.64-.13l.24,2.13h-3.76ZM44,48h-2.11l-.28-2.56c.84-.26,1.64-.63,2.39-1.06v3.62ZM38,44c-3.69,0-6.91-2.02-8.65-5h17.3c-1.74,2.98-4.96,5-8.65,5Z\"><\/path><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d15bee elementor-widget elementor-widget-heading\" data-id=\"4d15bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hts-mct.com\/fr\/secteurs-dactivite\/industries-de-transformation\/\">Industries de transformation<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1928c90 e-con-full e-flex e-con e-parent\" data-id=\"1928c90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-21008732 e-con-full e-flex e-con e-child\" data-id=\"21008732\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-451308d7 e-con-full e-flex e-con e-child\" data-id=\"451308d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44a251d1 elementor-widget elementor-widget-heading\" data-id=\"44a251d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une entreprise ax\u00e9e sur les personnes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f99ccdf elementor-widget elementor-widget-text-editor\" data-id=\"3f99ccdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La force de HTS r\u00e9side dans les personnes qui composent l\u2019entreprise. Leur exp\u00e9rience, leur expertise technique et leur engagement nous permettent de relever des d\u00e9fis complexes, de comprendre les besoins de nos clients et de proposer des solutions fiables adapt\u00e9es aux environnements les plus exigeants. Bien plus qu\u2019une simple \u00e9quipe, elles constituent le moteur de notre capacit\u00e9 \u00e0 innover, \u00e0 nous d\u00e9velopper et \u00e0 instaurer une confiance durable.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6721715 e-con-full e-flex e-con e-parent\" data-id=\"6721715\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9221ff1 elementor-widget elementor-widget-heading\" data-id=\"9221ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre parcours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e71c92 elementor-widget elementor-widget-text-editor\" data-id=\"3e71c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez les \u00e9tapes cl\u00e9s qui ont marqu\u00e9 l&rsquo;histoire de HTS, depuis ses d\u00e9buts en mer du Nord jusqu&rsquo;\u00e0 son essor en tant que fabricant europ\u00e9en d&rsquo;envergure mondiale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58e664fc e-con-full e-flex e-con e-parent\" data-id=\"58e664fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8c8675 elementor-pagination-position-inside elementor-pagination-type-bullets elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"6a8c8675\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;2005&quot;,&quot;_id&quot;:&quot;4e664ed&quot;},{&quot;slide_title&quot;:&quot;2010&quot;,&quot;_id&quot;:&quot;8ce29ab&quot;},{&quot;slide_title&quot;:&quot;2017&quot;,&quot;_id&quot;:&quot;8b53284&quot;},{&quot;slide_title&quot;:&quot;2020&quot;,&quot;_id&quot;:&quot;a20fe35&quot;},{&quot;slide_title&quot;:&quot;2023&quot;,&quot;_id&quot;:&quot;95d9c6e&quot;},{&quot;slide_title&quot;:&quot;2023&quot;,&quot;_id&quot;:&quot;4e70c54&quot;},{&quot;slide_title&quot;:&quot;2024&quot;,&quot;_id&quot;:&quot;6c027b5&quot;},{&quot;slide_title&quot;:&quot;2025&quot;,&quot;_id&quot;:&quot;bcbf348&quot;}],&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;autoplay_speed&quot;:3000,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52e9d832 e-flex e-con-boxed e-con e-child\" data-id=\"52e9d832\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59437b0 e-con-full e-flex e-con e-child\" data-id=\"59437b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b3554a elementor-widget elementor-widget-heading\" data-id=\"2b3554a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2005<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22d56ba elementor-widget elementor-widget-text-editor\" data-id=\"22d56ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>HTS rejoint le groupe Jove<\/strong><\/p><p>Jove Group rach\u00e8te Hawke Transit System \u00e0 Hawke International. Un nouveau chapitre s&rsquo;ouvre pour cette unit\u00e9 sp\u00e9cialis\u00e9e dans les solutions d&rsquo;\u00e9tanch\u00e9it\u00e9, qui nourrit des ambitions mondiales.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67690832 e-flex e-con-boxed e-con e-child\" data-id=\"67690832\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1573f9a e-con-full e-flex e-con e-child\" data-id=\"1573f9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0349b2e elementor-widget elementor-widget-heading\" data-id=\"0349b2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2010<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-074aefd elementor-widget elementor-widget-text-editor\" data-id=\"074aefd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Singapour : la porte d&rsquo;entr\u00e9e vers l&rsquo;Asie-Pacifique<\/strong><\/p><p>HTS Asia a \u00e9t\u00e9 cr\u00e9\u00e9e \u00e0 Singapour. Il s&rsquo;agit de la premi\u00e8re \u00e9tape d&rsquo;une expansion internationale qui s&rsquo;\u00e9tendra \u00e0 quatre continents au cours de la prochaine d\u00e9cennie. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26fe7330 e-flex e-con-boxed e-con e-child\" data-id=\"26fe7330\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a561ecc e-con-full e-flex e-con e-child\" data-id=\"a561ecc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bbfb80 elementor-widget elementor-widget-heading\" data-id=\"4bbfb80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2017<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fec1636 elementor-widget elementor-widget-text-editor\" data-id=\"fec1636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>HTS s&rsquo;implante au Royaume-Uni<\/strong><\/p><p>La soci\u00e9t\u00e9 HTS UK a \u00e9t\u00e9 constitu\u00e9e, ce qui permet de rapprocher l&rsquo;expertise de l&rsquo;entreprise de l&rsquo;un des march\u00e9s navals et offshore les plus dynamiques au monde.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7076176b e-flex e-con-boxed e-con e-child\" data-id=\"7076176b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77e859e e-con-full e-flex e-con e-child\" data-id=\"77e859e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bafec9e elementor-widget elementor-widget-heading\" data-id=\"bafec9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2020<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e877f6 elementor-widget elementor-widget-text-editor\" data-id=\"2e877f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>P\u00f4le logistique en Chine<\/strong><\/p><p>Un entrep\u00f4t d\u00e9di\u00e9 en Chine garantit des d\u00e9lais de r\u00e9ponse rapides dans toute l&rsquo;Asie. Une proximit\u00e9 avec le march\u00e9, soutenue par une capacit\u00e9 op\u00e9rationnelle. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282c28c e-flex e-con-boxed e-con e-child\" data-id=\"282c28c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9636ce2 e-con-full e-flex e-con e-child\" data-id=\"9636ce2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bae24fc elementor-widget elementor-widget-heading\" data-id=\"bae24fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2023<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbeaa54 elementor-widget elementor-widget-text-editor\" data-id=\"fbeaa54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Qingdao : un engagement \u00e0 long terme envers la Chine  <\/strong><\/p><p>Un bureau commercial ouvre ses portes \u00e0 Qingdao, ce qui t\u00e9moigne de la volont\u00e9 de HTS d&rsquo;assurer une pr\u00e9sence directe et durable sur l&rsquo;un des march\u00e9s les plus dynamiques en mati\u00e8re d&rsquo;infrastructures maritimes et industrielles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c571d30 e-flex e-con-boxed e-con e-child\" data-id=\"c571d30\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33b9e17 e-con-full e-flex e-con e-child\" data-id=\"33b9e17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bdcdb elementor-widget elementor-widget-heading\" data-id=\"f2bdcdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2023<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-031001a elementor-widget elementor-widget-text-editor\" data-id=\"031001a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Madrid : plus proche de l&rsquo;Europe du Sud<br><\/b><\/p><p>HTS ouvre un bureau \u00e0 Madrid, renfor\u00e7ant ainsi sa pr\u00e9sence en Europe du Sud et mettant son expertise technique \u00e0 la disposition de ses principaux clients de la r\u00e9gion.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"7\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-515f493 e-flex e-con-boxed e-con e-child\" data-id=\"515f493\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b4893cf e-con-full e-flex e-con e-child\" data-id=\"b4893cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0e9343 elementor-widget elementor-widget-heading\" data-id=\"e0e9343\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2024<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac472e7 elementor-widget elementor-widget-text-editor\" data-id=\"ac472e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>L&rsquo;Italie rejoint le r\u00e9seau<\/b><\/p><p>L&rsquo;ouverture d&rsquo;un nouveau bureau en Italie consolide la pr\u00e9sence de HTS dans la r\u00e9gion m\u00e9diterran\u00e9enne et renforce son ancrage op\u00e9rationnel en Europe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"8\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 8\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73867836 e-flex e-con-boxed e-con e-child\" data-id=\"73867836\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e7cd239 e-con-full e-flex e-con e-child\" data-id=\"e7cd239\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72a4e7a elementor-widget elementor-widget-heading\" data-id=\"72a4e7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1069a elementor-widget elementor-widget-text-editor\" data-id=\"df1069a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Moyen-Orient : l\u00e0 o\u00f9 les infrastructures \u00e9nerg\u00e9tiques exigent ce qu&rsquo;il y a de mieux<\/strong><\/p><p>HTS ouvre un bureau aux \u00c9mirats arabes unis, ce qui place l&rsquo;entreprise au c\u0153ur de l&rsquo;une des r\u00e9gions les plus dynamiques en mati\u00e8re de projets offshore, \u00e9nerg\u00e9tiques et d&rsquo;infrastructures critiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2da39cbb e-con-full e-flex e-con e-parent\" data-id=\"2da39cbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17596f93 elementor-widget elementor-widget-heading\" data-id=\"17596f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4595c71b elementor-widget elementor-widget-text-editor\" data-id=\"4595c71b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des entreprises de premier plan issues de nombreux secteurs nous font confiance<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e4052bd elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6e4052bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;10&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png\" alt=\"Logo Navantia - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-thames-water-hts-client-150x150.png\" alt=\"Logo Thames Water - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-equinor-hts-client-150x150.png\" alt=\"Logo Equinor- HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-telefonica-hts-client-150x150.png\" alt=\"Logo Telefonica - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-repsol-hts-client-150x150.png\" alt=\"Logo Repsol - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-sbm-offshore-hts-client-150x150.png\" alt=\"Logo SBM Offshore - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-conoco-hts-client-150x150.png\" alt=\"Logo Conoco Phillips - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2025\/07\/hawke-hts-exxonmobil-logo1-150x150.png\" alt=\"Logo Exxon Mobil\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-sellafield-hts-client-150x150.png\" alt=\"Logo Sellafield - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-santander-hts-client-150x150.png\" alt=\"Logo Santander - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-jacobs-hts-client-150x150.png\" alt=\"Logo Jacobs - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-dsme-hts-client-150x150.png\" alt=\"Logo DSME - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-national-grid-hts-client-150x150.png\" alt=\"Logo national grid - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-bauer-hts-client-150x150.png\" alt=\"Logo Bauer Kompresoren - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2025\/07\/hawke-hts-logo-bae-system-1-200x200-11-150x150.png\" alt=\"Logo BAE Systems\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-nestle-hts-client-150x150.png\" alt=\"Logo Nestle- HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-awe-hts-client-150x150.png\" alt=\"Logo AWE - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-BP-hts-client-150x150.png\" alt=\"Logo BP - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 sur 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-urenco-hts-client-150x150.png\" alt=\"Logo Urenco- HTS Client\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e77f9da elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e77f9da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;10&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-technip-hts-client-150x150.png\" alt=\"Logo Technip FMC - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2025\/07\/hawke-hts-logo-keppel-1-200x200-11-150x150.png\" alt=\"Logo Keppel\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-fincantieri-hts-client-150x150.png\" alt=\"Logo Fincantieri - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2025\/07\/hawke-hts-logo-shell-1-200x200-11-150x150.png\" alt=\"Logo Shell\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-aramco-hts-client-150x150.png\" alt=\"Logo Saudi Aramco - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-cbi-hts-client-150x150.png\" alt=\"Logo CBI - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-Bechtel-hts-client-150x150.png\" alt=\"Logo Bechtel - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-amec-foster-hts-client-150x150.png\" alt=\"Logo amec foster wheeler- HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-worley-hts-client-150x150.png\" alt=\"Logo worley- HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-kbr-hts-client-150x150.png\" alt=\"Logo KBR - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-caterpillar-hts-client-150x150.png\" alt=\"Logo Caterpillar - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-williams-hts-client-150x150.png\" alt=\"Logo Williams F1 - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-bombardier-hts-client-150x150.png\" alt=\"Logo Bombardier - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-siemens-hts-client-150x150.png\" alt=\"Logo Siemens - HTS Client\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 sur 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-GE-hts-client-150x150.png\" alt=\"Logo G&amp;E - HTS Client\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HTS Solutions de scellage de s\u00e9curit\u00e9 Fabricant europ\u00e9en de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 MCT HTS (Hawke Transit System), une soci\u00e9t\u00e9 du groupe JOVE, est sp\u00e9cialis\u00e9e dans la conception et la fabrication de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 pour le passage de c\u00e2bles multiples et de canalisations destin\u00e9s aux infrastructures critiques et aux environnements industriels exigeants. Forte de plus de 30 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-31880","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v25.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c0 propos de HTS - HTS MCT | Safety Sealing Solutions for Cables and Pipes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 propos de HTS\" \/>\n<meta property=\"og:description\" content=\"HTS Solutions de scellage de s\u00e9curit\u00e9 Fabricant europ\u00e9en de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 MCT HTS (Hawke Transit System), une soci\u00e9t\u00e9 du groupe JOVE, est sp\u00e9cialis\u00e9e dans la conception et la fabrication de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 pour le passage de c\u00e2bles multiples et de canalisations destin\u00e9s aux infrastructures critiques et aux environnements industriels exigeants. Forte de plus de 30 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/\" \/>\n<meta property=\"og:site_name\" content=\"HTS MCT | Safety Sealing Solutions for Cables and Pipes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/\",\"url\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/\",\"name\":\"\u00c0 propos de HTS - HTS MCT | Safety Sealing Solutions for Cables and Pipes\",\"isPartOf\":{\"@id\":\"https:\/\/hts-mct.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png\",\"datePublished\":\"2026-07-27T07:02:45+00:00\",\"dateModified\":\"2026-09-01T13:12:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage\",\"url\":\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png\",\"contentUrl\":\"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hts-mct.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos de HTS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hts-mct.com\/fr\/#website\",\"url\":\"https:\/\/hts-mct.com\/fr\/\",\"name\":\"HTS MCT | Safety Sealing Solutions for Cables and Pipes\",\"description\":\"Discover HTS MCT sealing solutions, designed to ensure safety and efficiency for cable and pipe penetrations. Reliable protection for the most demanding environments.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hts-mct.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c0 propos de HTS - HTS MCT | Safety Sealing Solutions for Cables and Pipes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 propos de HTS","og_description":"HTS Solutions de scellage de s\u00e9curit\u00e9 Fabricant europ\u00e9en de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 MCT HTS (Hawke Transit System), une soci\u00e9t\u00e9 du groupe JOVE, est sp\u00e9cialis\u00e9e dans la conception et la fabrication de syst\u00e8mes d&rsquo;\u00e9tanch\u00e9it\u00e9 pour le passage de c\u00e2bles multiples et de canalisations destin\u00e9s aux infrastructures critiques et aux environnements industriels exigeants. Forte de plus de 30 [&hellip;]","og_url":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/","og_site_name":"HTS MCT | Safety Sealing Solutions for Cables and Pipes","article_modified_time":"2026-09-01T13:12:03+00:00","og_image":[{"url":"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/","url":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/","name":"\u00c0 propos de HTS - HTS MCT | Safety Sealing Solutions for Cables and Pipes","isPartOf":{"@id":"https:\/\/hts-mct.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage"},"image":{"@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png","datePublished":"2026-07-27T07:02:45+00:00","dateModified":"2026-09-01T13:12:03+00:00","breadcrumb":{"@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#primaryimage","url":"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png","contentUrl":"https:\/\/hts-mct.com\/wp-content\/uploads\/2026\/08\/logo-navantia-hts-client-150x150.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hts-mct.com\/fr\/a-propos-de-hts-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hts-mct.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos de HTS"}]},{"@type":"WebSite","@id":"https:\/\/hts-mct.com\/fr\/#website","url":"https:\/\/hts-mct.com\/fr\/","name":"HTS MCT | Safety Sealing Solutions for Cables and Pipes","description":"Discover HTS MCT sealing solutions, designed to ensure safety and efficiency for cable and pipe penetrations. Reliable protection for the most demanding environments.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hts-mct.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/pages\/31880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/comments?post=31880"}],"version-history":[{"count":2,"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/pages\/31880\/revisions"}],"predecessor-version":[{"id":31882,"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/pages\/31880\/revisions\/31882"}],"wp:attachment":[{"href":"https:\/\/hts-mct.com\/fr\/wp-json\/wp\/v2\/media?parent=31880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}